{"id":5923,"date":"2020-04-03T16:32:33","date_gmt":"2020-04-03T19:32:33","guid":{"rendered":"http:\/\/reydereyes.com.ar\/?p=5923"},"modified":"2022-01-04T13:03:23","modified_gmt":"2022-01-04T16:03:23","slug":"cuida-tu-corazon","status":"publish","type":"post","link":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/","title":{"rendered":"\"Take care of your heart\" - Dr. Claudio Freidzon"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.4.4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0.5)&#8221; background_color_gradient_end=&#8221;rgba(0,0,0,0)&#8221; background_color_gradient_direction=&#8221;1deg&#8221; background_image=&#8221;http:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/04\/FOTO-CUIDA-TU-CORAZ\u00d3N.jpg&#8221; background_blend=&#8221;multiply&#8221; custom_padding=&#8221;||0px||false|false&#8221;][et_pb_row custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.4.4&#8243; width=&#8221;100%&#8221; custom_padding=&#8221;250px|||||&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;250px|40px||40px|false|true&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.4.4&#8243;][et_pb_post_title author=&#8221;off&#8221; date=&#8221;off&#8221; categories=&#8221;off&#8221; comments=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.7.1&#8243; title_font=&#8221;Montserrat|800||on|||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#ffffff&#8221; meta_text_align=&#8221;center&#8221; meta_text_color=&#8221;#ffffff&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_post_title][et_pb_text _builder_version=&#8221;4.4.4&#8243; text_text_color=&#8221;#0c71c3&#8243; background_enable_color=&#8221;off&#8221; custom_padding=&#8221;||||true|true&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Tiempo de lectura: 3 minutos<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243;][et_pb_row custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.4.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;|10%||10%|false|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;|2%||2%|false|true&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.4.4&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#333333&#8243; background_color=&#8221;#fafafa&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Todo lo que tiene comuni\u00f3n con Dios, debe ser santo. El Dr. Claudio Freidzon nos invita a guardar nuestros corazones a\u00fan en medio de las dificultades.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.4.4&#8243; text_text_color=&#8221;#333333&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>Naam\u00e1n fue un general muy importante del ej\u00e9rcito sirio. Relata el libro de Segunda de Reyes en el cap\u00edtulo 5, que durante una de sus incursiones invadiendo la tierra de Israel al mando de sus tropas, tom\u00f3 como bot\u00edn a varias familias hebreas para que le fuera de servidumbre.<\/p>\n<p>Este hombre, muy importante para su rey, ocultaba un serio problema de salud. Debajo de su armadura y sus vestiduras, la lepra, una enfermedad incurable iba minando todo su cuerpo.<\/p>\n<p>La Biblia toma a la lepra como un ejemplo del pecado; \u00e9ste hace que el hombre vaya alej\u00e1ndose poco a poco de los prop\u00f3sistos de Dios.<\/p>\n<p>S\u00f3lo Cristo puede limpiar el pecado. S\u00f3lo Cristo puede perdonar nuestras vidas\u2026\u00a1s\u00f3lo Cristo nos puede hacer libres!<\/p>\n<p>Retomando la historia; una vez que la sierva de este militar lo ve tan enfermo, le habla de la persona de Eliseo, \u201cun profeta del verdadero Dios\u201d que lo puede sanar.<\/p>\n<p>As\u00ed fue que este hombre termina yendo a la tierra donde se encontraba Eliseo, quien no lo recibe personalmente y, m\u00e1s a\u00fan, le es indicado por su asistente que la soluci\u00f3n para su lepra es que vaya a ba\u00f1arse al r\u00edo Jord\u00e1n.<\/p>\n<p>Ya sabemos que luego del enojo incial y las negativas de Naam\u00e1n, la \u201cs\u00e9ptima zambullida\u201d dej\u00f3 limpia por completo la piel de este general.<\/p>\n<p>El desarraigo de aquella joven que fue una criada de la casa del general sirio y, a\u00fan la adversidad de encontrarse lejos de su hogar y en medio de costumbres y creencias extra\u00f1as, no consigui\u00f3 que su coraz\u00f3n fuera conmovido, porque supo depositar su fe y esperanza en un Dios poderoso.<\/p>\n<p>Ese mismo Dios de Israel es el que hoy est\u00e1 aqu\u00ed para cambiar las circunstancias y transformar los corazones y, as\u00ed como esa joven pudo dar testmonio de un Dios vivo, hoy el llamado es a que tu fe no se quebrante; que tus convicciones no se alejen.<\/p>\n<p>Que estando en una tierra donde la gente no adora al verdadero Dios, que nuestros corazones sigan siendo fieles al Dios que no cambia.<\/p>\n<p><strong>\u00a1Cuida tu coraz\u00f3n!<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;http:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/03\/rdr_logo-1.jpeg&#8221; title_text=&#8221;rdr_logo&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.4.4&#8243; max_width=&#8221;120px&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.4.4&#8243; background_color=&#8221;#fafafa&#8221; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;||||false|false&#8221; locked=&#8221;off&#8221;][et_pb_row _builder_version=&#8221;4.4.4&#8243; custom_margin=&#8221;0px||0px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.4.4&#8243;][et_pb_post_nav in_same_term=&#8221;on&#8221; _builder_version=&#8221;4.4.4&#8243; title_font=&#8221;|700|||||||&#8221;][\/et_pb_post_nav][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Everything that has communion with God must be holy. Dr. Claudio Freidzon invites us to keep our hearts even in the midst of difficulties.<\/p>","protected":false},"author":3,"featured_media":5934,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p><strong>Todo lo que tiene comuni\u00f3n con Dios, debe ser santo. El Dr. Claudio Freidzon nos invita a guardar nuestros corazones a\u00fan en medio de las dificultades.<\/strong><\/p><p>Naam\u00e1n fue un general muy importante del ej\u00e9rcito sirio. Relata el libro de Segunda de Reyes en el cap\u00edtulo 5, que durante una de sus incursiones invadiendo la tierra de Israel al mando de sus tropas, tom\u00f3 como bot\u00edn a varias familias hebreas para que le fuera de servidumbre.<\/p><p>Este hombre, muy importante para su rey, ocultaba un serio problema de salud. Debajo de su armadura y sus vestiduras, la lepra, una enfermedad incurable iba minando todo su cuerpo.<\/p><p>La Biblia toma a la lepra como un ejemplo del pecado; \u00e9ste hace que el hombre vaya alej\u00e1ndose poco a poco de los prop\u00f3sistos de Dios.<\/p><p>S\u00f3lo Cristo puede limpiar el pecado. S\u00f3lo Cristo puede perdonar nuestras vidas\u2026\u00a1s\u00f3lo Cristo nos puede hacer libres!<\/p><p>Retomando la historia; una vez que la sierva de este militar lo ve tan enfermo, le habla de la persona de Eliseo, \u201cun profeta del verdadero Dios\u201d que lo puede sanar.<\/p><p>As\u00ed fue que este hombre termina yendo a la tierra donde se encontraba Eliseo, quien no lo recibe personalmente y, m\u00e1s a\u00fan, le es indicado por su asistente que la soluci\u00f3n para su lepra es que vaya a ba\u00f1arse al r\u00edo Jord\u00e1n.<\/p><p>Ya sabemos que luego del enojo incial y las negativas de Naam\u00e1n, la \u201cs\u00e9ptima zambullida\u201d dej\u00f3 limpia por completo la piel de este general.<\/p><p>El desarraigo de aquella joven que fue una criada de la casa del general sirio y, a\u00fan la adversidad de encontrarse lejos de su hogar y en medio de costumbres y creencias extra\u00f1as, no consigui\u00f3 que su coraz\u00f3n fuera conmovido, porque supo depositar su fe y esperanza en un Dios poderoso.<\/p><p>Ese mismo Dios de Israel es el que hoy est\u00e1 aqu\u00ed para cambiar las circunstancias y transformar los corazones y, as\u00ed como esa joven pudo dar testmonio de un Dios vivo, hoy el llamado es a que tu fe no se quebrante; que tus convicciones no se alejen.<\/p><p>Que estando en una tierra donde la gente no adora al verdadero Dios, que nuestros corazones sigan siendo fieles al Dios que no cambia.<\/p><p><strong>\u00a1Cuida tu coraz\u00f3n!<\/strong><\/p>","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-5923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mensajes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Todo lo que tiene comuni\u00f3n con Dios, debe ser santo. El Dr. Claudio Freidzon nos invita a guardar nuestros corazones a\u00fan en medio de las dificultades.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Rdr Admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"google4e9393a295af783a\" \/>\n\t<meta name=\"msvalidate.01\" content=\"1bc4ed2835b147158c0de70a28415b39\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Iglesia Rey de Reyes - Sitio Web Oficial\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cuida tu coraz\u00f3n - Pr\u00e9dica del Dr. Claudio Freidzon\" \/>\n\t\t<meta property=\"og:description\" content=\"Todo lo que tiene comuni\u00f3n con Dios, debe ser santo. El Dr. Claudio Freidzon nos invita a guardar nuestros corazones a\u00fan en medio de las dificultades.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/04\/FOTO-CUIDA-TU-CORAZ\u00d3N.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/04\/FOTO-CUIDA-TU-CORAZ\u00d3N.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t\t<meta property=\"article:section\" content=\"Mensajes\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-04-03T19:32:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-01-04T16:03:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Iglesia-Rey-de-Reyes-137743276296202\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@iglereydereyes\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cuida tu coraz\u00f3n - Pr\u00e9dica del Dr. Claudio Freidzon\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Todo lo que tiene comuni\u00f3n con Dios, debe ser santo. El Dr. Claudio Freidzon nos invita a guardar nuestros corazones a\u00fan en medio de las dificultades.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@iglereydereyes\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/04\/FOTO-CUIDA-TU-CORAZ\u00d3N.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Rdr Admin\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#article\",\"name\":\"Cuida tu coraz\\u00f3n - Pr\\u00e9dica del Dr. Claudio Freidzon\",\"headline\":\"&#8220;Cuida tu coraz\\u00f3n&#8221; &#8211; Dr. Claudio Freidzon\",\"author\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/author\\\/rdr_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/reydereyes.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/FOTO-CUIDA-TU-CORAZ\\u00d3N.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Pastor Claudio Freidzon\"},\"datePublished\":\"2020-04-03T16:32:33-03:00\",\"dateModified\":\"2022-01-04T13:03:23-03:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#webpage\"},\"articleSection\":\"Mensajes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/category\\\/mensajes\\\/#listItem\",\"name\":\"Mensajes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/category\\\/mensajes\\\/#listItem\",\"position\":2,\"name\":\"Mensajes\",\"item\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/category\\\/mensajes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#listItem\",\"name\":\"&#8220;Cuida tu coraz\\u00f3n&#8221; &#8211; Dr. Claudio Freidzon\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#listItem\",\"position\":3,\"name\":\"&#8220;Cuida tu coraz\\u00f3n&#8221; &#8211; Dr. Claudio Freidzon\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/category\\\/mensajes\\\/#listItem\",\"name\":\"Mensajes\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/#organization\",\"name\":\"Iglesia Rey de Reyes\",\"description\":\"Sitio Web Oficial de la Iglesia Rey de Reyes, Belgrano, Buenos Aires, Argentina.\",\"url\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/\",\"telephone\":\"+541147890047\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/reydereyes.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo_round_black.png\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#organizationLogo\",\"width\":178,\"height\":180,\"caption\":\"Logo negro de la Iglesia Rey de Reyes\"},\"image\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Iglesia-Rey-de-Reyes-137743276296202\\\/\",\"https:\\\/\\\/twitter.com\\\/iglereydereyes\",\"https:\\\/\\\/www.instagram.com\\\/iglereydereyes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCmXRujtSJ_ni8o1Gkun7__g\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/iglesia-rey-de-reyes-ok\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/author\\\/rdr_admin\\\/#author\",\"url\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/author\\\/rdr_admin\\\/\",\"name\":\"Rdr Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5839cfdf2eb153f5e778bbd573e3452a2aa4f2cf1c3fe41887169c1e57ea130?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Rdr Admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#webpage\",\"url\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/\",\"name\":\"Cuida tu coraz\\u00f3n - Pr\\u00e9dica del Dr. Claudio Freidzon\",\"description\":\"Todo lo que tiene comuni\\u00f3n con Dios, debe ser santo. El Dr. Claudio Freidzon nos invita a guardar nuestros corazones a\\u00fan en medio de las dificultades.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/author\\\/rdr_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/author\\\/rdr_admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/reydereyes.com.ar\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/FOTO-CUIDA-TU-CORAZ\\u00d3N.jpg\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#mainImage\",\"width\":1920,\"height\":1280,\"caption\":\"Pastor Claudio Freidzon\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/cuida-tu-corazon\\\/#mainImage\"},\"datePublished\":\"2020-04-03T16:32:33-03:00\",\"dateModified\":\"2022-01-04T13:03:23-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/\",\"name\":\"Iglesia Rey de Reyes - Sitio Web Oficial\",\"description\":\"Sitio Web Oficial de la Iglesia Rey de Reyes, Belgrano, Buenos Aires, Argentina.\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/reydereyes.com.ar\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cuida tu coraz\u00f3n - Pr\u00e9dica del Dr. Claudio Freidzon","description":"Everything that has communion with God must be holy. Dr. Claudio Freidzon invites us to keep our hearts even in the midst of difficulties.","canonical_url":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"google4e9393a295af783a","msvalidate.01":"1bc4ed2835b147158c0de70a28415b39","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#article","name":"Cuida tu coraz\u00f3n - Pr\u00e9dica del Dr. Claudio Freidzon","headline":"&#8220;Cuida tu coraz\u00f3n&#8221; &#8211; Dr. Claudio Freidzon","author":{"@id":"https:\/\/reydereyes.com.ar\/en\/author\/rdr_admin\/#author"},"publisher":{"@id":"https:\/\/reydereyes.com.ar\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/04\/FOTO-CUIDA-TU-CORAZ\u00d3N.jpg","width":1920,"height":1280,"caption":"Pastor Claudio Freidzon"},"datePublished":"2020-04-03T16:32:33-03:00","dateModified":"2022-01-04T13:03:23-03:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#webpage"},"isPartOf":{"@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#webpage"},"articleSection":"Mensajes"},{"@type":"BreadcrumbList","@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/reydereyes.com.ar\/en#listItem","position":1,"name":"Inicio","item":"https:\/\/reydereyes.com.ar\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/reydereyes.com.ar\/en\/category\/mensajes\/#listItem","name":"Mensajes"}},{"@type":"ListItem","@id":"https:\/\/reydereyes.com.ar\/en\/category\/mensajes\/#listItem","position":2,"name":"Mensajes","item":"https:\/\/reydereyes.com.ar\/en\/category\/mensajes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#listItem","name":"&#8220;Cuida tu coraz\u00f3n&#8221; &#8211; Dr. Claudio Freidzon"},"previousItem":{"@type":"ListItem","@id":"https:\/\/reydereyes.com.ar\/en#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#listItem","position":3,"name":"&#8220;Cuida tu coraz\u00f3n&#8221; &#8211; Dr. Claudio Freidzon","previousItem":{"@type":"ListItem","@id":"https:\/\/reydereyes.com.ar\/en\/category\/mensajes\/#listItem","name":"Mensajes"}}]},{"@type":"Organization","@id":"https:\/\/reydereyes.com.ar\/en\/#organization","name":"Iglesia Rey de Reyes","description":"Sitio Web Oficial de la Iglesia Rey de Reyes, Belgrano, Buenos Aires, Argentina.","url":"https:\/\/reydereyes.com.ar\/en\/","telephone":"+541147890047","logo":{"@type":"ImageObject","url":"https:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/03\/logo_round_black.png","@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#organizationLogo","width":178,"height":180,"caption":"Logo negro de la Iglesia Rey de Reyes"},"image":{"@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/Iglesia-Rey-de-Reyes-137743276296202\/","https:\/\/twitter.com\/iglereydereyes","https:\/\/www.instagram.com\/iglereydereyes\/","https:\/\/www.youtube.com\/channel\/UCmXRujtSJ_ni8o1Gkun7__g","https:\/\/www.linkedin.com\/company\/iglesia-rey-de-reyes-ok\/"]},{"@type":"Person","@id":"https:\/\/reydereyes.com.ar\/en\/author\/rdr_admin\/#author","url":"https:\/\/reydereyes.com.ar\/en\/author\/rdr_admin\/","name":"Rdr Admin","image":{"@type":"ImageObject","@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e5839cfdf2eb153f5e778bbd573e3452a2aa4f2cf1c3fe41887169c1e57ea130?s=96&d=mm&r=g","width":96,"height":96,"caption":"Rdr Admin"}},{"@type":"WebPage","@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#webpage","url":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/","name":"Cuida tu coraz\u00f3n - Pr\u00e9dica del Dr. Claudio Freidzon","description":"Todo lo que tiene comuni\u00f3n con Dios, debe ser santo. El Dr. Claudio Freidzon nos invita a guardar nuestros corazones a\u00fan en medio de las dificultades.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/reydereyes.com.ar\/en\/#website"},"breadcrumb":{"@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#breadcrumblist"},"author":{"@id":"https:\/\/reydereyes.com.ar\/en\/author\/rdr_admin\/#author"},"creator":{"@id":"https:\/\/reydereyes.com.ar\/en\/author\/rdr_admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/04\/FOTO-CUIDA-TU-CORAZ\u00d3N.jpg","@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#mainImage","width":1920,"height":1280,"caption":"Pastor Claudio Freidzon"},"primaryImageOfPage":{"@id":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/#mainImage"},"datePublished":"2020-04-03T16:32:33-03:00","dateModified":"2022-01-04T13:03:23-03:00"},{"@type":"WebSite","@id":"https:\/\/reydereyes.com.ar\/en\/#website","url":"https:\/\/reydereyes.com.ar\/en\/","name":"Iglesia Rey de Reyes - Sitio Web Oficial","description":"Sitio Web Oficial de la Iglesia Rey de Reyes, Belgrano, Buenos Aires, Argentina.","inLanguage":"en-US","publisher":{"@id":"https:\/\/reydereyes.com.ar\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Iglesia Rey de Reyes - Sitio Web Oficial","og:type":"article","og:title":"Cuida tu coraz\u00f3n - Pr\u00e9dica del Dr. Claudio Freidzon","og:description":"Todo lo que tiene comuni\u00f3n con Dios, debe ser santo. El Dr. Claudio Freidzon nos invita a guardar nuestros corazones a\u00fan en medio de las dificultades.","og:url":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/","og:image":"https:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/04\/FOTO-CUIDA-TU-CORAZ\u00d3N.jpg","og:image:secure_url":"https:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/04\/FOTO-CUIDA-TU-CORAZ\u00d3N.jpg","og:image:width":1920,"og:image:height":1280,"article:section":"Mensajes","article:published_time":"2020-04-03T19:32:33+00:00","article:modified_time":"2022-01-04T16:03:23+00:00","article:publisher":"https:\/\/www.facebook.com\/Iglesia-Rey-de-Reyes-137743276296202\/","twitter:card":"summary_large_image","twitter:site":"@iglereydereyes","twitter:title":"Cuida tu coraz\u00f3n - Pr\u00e9dica del Dr. Claudio Freidzon","twitter:description":"Todo lo que tiene comuni\u00f3n con Dios, debe ser santo. El Dr. Claudio Freidzon nos invita a guardar nuestros corazones a\u00fan en medio de las dificultades.","twitter:creator":"@iglereydereyes","twitter:image":"https:\/\/reydereyes.com.ar\/wp-content\/uploads\/2020\/04\/FOTO-CUIDA-TU-CORAZ\u00d3N.jpg","twitter:label1":"Written by","twitter:data1":"Rdr Admin","twitter:label2":"Est. reading time","twitter:data2":"4 minutes"},"aioseo_meta_data":{"post_id":"5923","title":"Cuida tu coraz\u00f3n - Pr\u00e9dica del Dr. Claudio Freidzon","description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"featured","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":"Mensajes","og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":"Cuida tu coraz\u00f3n - Pr\u00e9dica del Dr. Claudio Freidzon","twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2022-04-29 23:38:53","updated":"2025-06-04 18:13:31","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/reydereyes.com.ar\/en\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/reydereyes.com.ar\/en\/category\/mensajes\/\" title=\"Mensajes\">Mensajes<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u201cCuida tu coraz\u00f3n\u201d \u2013 Dr. Claudio Freidzon\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/reydereyes.com.ar\/en"},{"label":"Mensajes","link":"https:\/\/reydereyes.com.ar\/en\/category\/mensajes\/"},{"label":"&#8220;Cuida tu coraz\u00f3n&#8221; &#8211; Dr. Claudio Freidzon","link":"https:\/\/reydereyes.com.ar\/en\/cuida-tu-corazon\/"}],"_links":{"self":[{"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/posts\/5923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/comments?post=5923"}],"version-history":[{"count":36,"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/posts\/5923\/revisions"}],"predecessor-version":[{"id":15714,"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/posts\/5923\/revisions\/15714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/media\/5934"}],"wp:attachment":[{"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/media?parent=5923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/categories?post=5923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reydereyes.com.ar\/en\/wp-json\/wp\/v2\/tags?post=5923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}